{"id":279,"count":1,"description":"","link":"https:\/\/www.berliner-baerenfreunde.de\/web\/category\/east-side-mall\/","name":"EAST SIDE MALL","slug":"east-side-mall","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/categories\/279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts?categories=279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}