{"id":303,"count":1,"description":"","link":"https:\/\/www.berliner-baerenfreunde.de\/web\/category\/intimate-matter\/","name":"Intimate Matter","slug":"intimate-matter","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/categories\/303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts?categories=303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}