{"id":13018,"date":"2019-04-05T17:23:27","date_gmt":"2019-04-05T15:23:27","guid":{"rendered":"https:\/\/www.berliner-baerenfreunde.de\/web\/?p=13018"},"modified":"2019-05-20T10:32:44","modified_gmt":"2019-05-20T08:32:44","slug":"1994-das-baerenjahr-im-berliner-baerenzwinger","status":"publish","type":"post","link":"https:\/\/www.berliner-baerenfreunde.de\/web\/1994-das-baerenjahr-im-berliner-baerenzwinger\/","title":{"rendered":"1994 &#8211; das B\u00e4renjahr im Berliner B\u00e4renzwinger"},"content":{"rendered":"<p><em><strong>1994 war das Jahr der B\u00e4ren in Berlin. <\/strong><\/em><\/p>\n<p><!--more--><\/p>\n\n\n<p><br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"> <em>1994 &#8211; das B\u00e4renjahr<\/em><br><\/h2>\n\n\n\n<p>F\u00fcnf kleine B\u00e4renkinder, ein P\u00e4rchen, die Erstgeburten von Maxi, geboren am 7. Januar 1994 und zwei B\u00e4renjungen und ein B\u00e4renm\u00e4dchen, der f\u00fcnfte Wurf von Schnute, geboren am 13. Januar 1994, kamen als echte Berliner zur Welt. Welche Sensation. Gro\u00dfe Freude herrschte bei den Berlinern, die mit Spannung den ersten Auftritt entgegensahen. Dabei war der B\u00e4rennachwuchs keineswegs geplant. Tilo wurde durch einen medizinischen Eingriff die M\u00f6glichkeit genommen, Vater zu werden, weil der Zwinger nur f\u00fcr drei B\u00e4ren Platz bietet und kleine B\u00e4rchen kaum noch untergebracht werden k\u00f6nnen.<\/p>\n\n\n\n<p>ngg_shortcode_0_placeholder  ngg_shortcode_1_placeholder  ngg_shortcode_2_placeholder <br>Am Freitag, dem 22. April 1994, durften die B\u00e4renm\u00fctter mit ihren Kindern das erste Mal ihren K\u00e4fig verlassen und wurden von hunderten Berlinern mit Jubel begr\u00fc\u00dft. Tagt\u00e4glich besuchten viele B\u00e4renfreunde den Zwinger. Reisebusse und Stadtrundfahrten hielten noch \u00f6fter dort, um den G\u00e4sten die muntere B\u00e4renschar zu zeigen. Es war r\u00fchrend anzusehen, wie liebevoll und z\u00e4rtlich, aufmerksam und umsichtig Maxi und Schnute ihre B\u00e4rchen ins Leben f\u00fchrten. Am 20. Mai 1994 war B\u00e4rentaufe und obwohl es in Str\u00f6men regnete waren viele Berliner gekommen, die der Namensgebung durch den damaligen B\u00fcrgermeister des Bezirkes Mitte, Gerhard Keil, unbedingt beiwohnen wollten. In Anwesenheit von Presse, Funk und Fernsehen wurden die B\u00e4renkinder von Maxi auf B\u00e4rolina und Alex und die von Schnute auf Rieke, Atze und Piefke getauft. Nat\u00fcrlich entstammen diese Namen wiederum den Vorschl\u00e4gen der Berliner. <br>Unentwegt mu\u00dften die um ihre B\u00e4ren r\u00fchrend besorgten Pflegerinnen, Fragen der interessierten Besucher zu ihren Lieblingen beantworten. Betroffenheit und Wehmut zeichnete die Gesichter, wenn erkl\u00e4rt werden mu\u00dfte, da\u00df der Zwinger nur Platz f\u00fcr drei erwachsene B\u00e4ren bietet und die kleinen nach wenigen Monaten abgegeben werden m\u00fcssen. Der Bezirk Mitte und die Stadt Berlin suchten nach L\u00f6sungen, aber es gab wenig Interessenten. Kommunen in aller Welt haben wenig Geld, um neue B\u00e4ren und ihren Unterhalt zu finanzieren. <\/p>\n\n\n\n<p> ngg_shortcode_3_placeholder  ngg_shortcode_4_placeholder  ngg_shortcode_5_placeholder Ganze Berge von Briefen und viele Bitten wurden von den Berlinern an den Berliner Regierenden B\u00fcrgermeister und den B\u00fcrgermeister von Mitte gerichtet, sich f\u00fcr die B\u00e4rchen einzusetzen. Die schrieben wiederum an zoologische Einrichtungen in der ganzen Welt, um die Jungb\u00e4ren artgerecht unterzubringen. Viele Spenden gingen ein, um der Stadt die Sicherung der Zukunft der B\u00e4rchen zu erleichtern. <br> Der Regierende B\u00fcrgermeister bot allen Partnerst\u00e4dten Berlins die kleinen B\u00e4ren als Geschenk an, aber die meisten lehnten ab. Gro\u00df war dann die Freude als bekannt wurde, da\u00df die argentinische Hauptstadt Buenos Aires an drei B\u00e4ren interessiert ist. <br> Nat\u00fcrlich h\u00e4tten die Berliner ihre B\u00e4rchen am liebsten behalten. Aber solche spektakul\u00e4ren Schlagzeilen in der Presse, die Todesspritzen und anderes ank\u00fcndigten, wenn die B\u00e4rchen nicht untergebracht werden k\u00f6nnen, hinterlie\u00dfen Wirkung. Deshalb wurde die Kunde, da\u00df Buenos Aires eine artgerechte Haltung in einer neu erbauten sch\u00f6nen Anlage gew\u00e4hrleistet, mit Freude aufgenommen. <\/p>\n\n\n\n<p><br> Am 17.8.1994, genau zum 55.Jahrestag der Einweihung des B\u00e4renzwingers, war die Stunde des Abschieds gekommen. B\u00e4rolina, Rieke und Atze wurden vom B\u00fcrgermeister des Bezirkes Mitte, Gerhard Keil, \u00f6ffentlich und feierlich verabschiedet. <br> Wieder waren viele Berliner B\u00e4renfreunde anwesend, traurig \u00fcber den Abschied, aber gleichzeitig erfreut \u00fcber die Gewi\u00dfheit, da\u00df es den B\u00e4ren im Zoo von Buenos Aires gut gehen wird. Am 22.8.1994 mu\u00dften sie die weite Reise nach S\u00fcdamerika per Flugzeug antreten. Viele Berliner und fast alle Medien waren dabei, als es losging. Viele Tr\u00e4nen sind geflossen, als sie mit lautem Gebr\u00fcll in ihre Transportkisten verladen wurden. So sind nun einmal die Berliner. Das ist die echte Volksseele mit viel Herz. Die kleinen B\u00e4ren \u00fcberwanden die Trennung von ihren M\u00fcttern und der Berliner Kinderstube schnell. Sie wurden von einer ihrer Pflegerinnen auf ihrer Reise begleitet und hatten sie noch einige Tage zur Eingew\u00f6hnung in der neuen Anlage bei sich. Sie wurden auch mit gro\u00dfem Bahnhof in Buenos Aires empfangen und mit viel Liebe von den argentinischen Hauptst\u00e4dtern aufgenommen. Eine Bronzetafel weist sie mit ihren Berliner Namen als Geschenk des Regierenden B\u00fcrgermeisters von Berlin, Eberhard Diepgen, aus.   ngg_shortcode_6_placeholder   <\/p>\n\n\n\n<p><br> Nun waren Alex und Piefke unterzubringen. Der B\u00fcrgermeister von Mitte hatte erneut an 178 zoologische Einrichtungen geschrieben, um sie unterzubringen und die Berliner bangten weiter. Schlie\u00dflich fanden auch sie eine neue Heimat im Naturpark Cabarceno in der N\u00e4he der Stadt Santander in Nordspanien. Am 21. November 1994 wurden sie von den Berliner B\u00e4renfreunden verabschiedet. Wiederum konnte eine Pflegerin sie begleiten. Nach einer Eingew\u00f6hnungsphase konnten sie in der freien Natur leben, zusammen mit \u00fcber 50 anderen B\u00e4ren. So endete das gro\u00dfe B\u00e4renjahr der Berliner Wappentiere.<\/p>\n\n\n\n<p><br><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>1994 war das Jahr der B\u00e4ren in Berlin.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,153,157,204,266,3],"tags":[],"class_list":["post-13018","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-baerenkinder-von-1994","category-berliner-baerenzwinger","category-berliner-stadtbaeren","category-jahr-2019","category-topthema"],"_links":{"self":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts\/13018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/comments?post=13018"}],"version-history":[{"count":38,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts\/13018\/revisions"}],"predecessor-version":[{"id":13372,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts\/13018\/revisions\/13372"}],"wp:attachment":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/media?parent=13018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/categories?post=13018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/tags?post=13018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}