{"id":14204,"date":"2019-11-12T13:30:28","date_gmt":"2019-11-12T12:30:28","guid":{"rendered":"https:\/\/www.berliner-baerenfreunde.de\/web\/?p=14204"},"modified":"2019-11-15T18:11:42","modified_gmt":"2019-11-15T17:11:42","slug":"der-naechste-act","status":"publish","type":"post","link":"https:\/\/www.berliner-baerenfreunde.de\/web\/der-naechste-act\/","title":{"rendered":"Der n\u00e4chste Act"},"content":{"rendered":"<p>\u00bbMy Fiction and You\u00ab<!--more-->\u00bbMy Fiction and You\u00ab<\/p>\n<p>ngg_shortcode_0_placeholderDer n\u00e4chste Termin f\u00fcr eine Kunstaktion im B\u00e4renzwinger war f\u00e4llig; am Donnerstag, dem 7. November 2019 wurde die Ausstellung \u00bbMy Fiction and You\u00ab er\u00f6ffnet.<\/p>\n<p>Sie untersucht, wie Fiction und Imagination zum Bestandteil der eigenen Realit\u00e4t werden und inwiefern diese kollektiviert werden und sich zum Teil des sozialen Umfeldes entwickeln.<\/p>\n<p>ngg_shortcode_1_placeholderIn einem der \u201eB\u00e4rengehege\u201c war eine Wohnung nachempfunden; ein Wohnzimmer mit Tapete, Tisch, St\u00fchlen und einem Fernseher. Der gedachte Hintergrund dazu: die Lage auf dem Wohnungsmarkt hat sich auch mit dem Mietendeckel nicht entspannt und so kamen Investor*innen und Immobilienmakler*innen umgehend auf die Idee: wir machen jetzt auch neue Objekte bewohnbar. Kulturstandorte sollten doch auch zu Luxuswohnraum umfunktioniert werden, denn Institutionen der Kunst und Kultur geh\u00f6ren l\u00e4ngst zu den Relikten zivilisatorischer Vergangenheit. Diese Version verfolgt Andy Kassier in der Rolle des Provokateurs, dem jedes Mittel Recht ist, grenzenlos Profit herauszuschlagen.<\/p>\n<p>Eigentlich sehr bizarr, aber wenn man sich damit besch\u00e4ftigt: es ist durchaus denkbar, denn so h\u00e4tte der Senat\/ das Bezirksamt keine Probleme mit der Denkmalpflege, der \u201eBespielung\u201c des Kulturobjektes. Aber wohl gemerkt; es ist nur ein Gedankenspiel.<\/p>\n<p>ngg_shortcode_2_placeholderEin anderes Kunstobjekt ist ein gro\u00dfer Glascontainer. Man sieht hinein und erkennt nur den Naturboden des Au\u00dfengel\u00e4ndes, aber es spiegeln sich auch die B\u00e4ume, Bl\u00e4tter und man sieht sich selbst. Auch in den Seitenfl\u00e4chen sieht man sich selbst Laufen oder Stehen. Es scheint so, als ob sich im Glaskontainer alles aus der Umgebung sammmelt und es an einigen Stellen fokussiert.<\/p>\n<p>Andere Ausstellungsexponate waren auf der Basis der 3D Technik und von der digitalen Gegenwart gepr\u00e4gt. Mit den Tabletts konnte man auf \u201ePostkarten\u201c \u201eklicken\u201c und die wurden zum neuen Leben erweckt. Eine Tarotspiel zerlegte sich in einzelne Karten, ein Essensbild zeigte, wie man die Speise zubereitet.<\/p>\n<p>Leider konnte ich diese Objekte nicht genie\u00dfen, da ich dazu passende Technik nicht besitze. Dieser Teil der Ausstellung war also (im wahrsten Sinne des Wortes) nichts f\u00fcr mich. Aber das j\u00fcngere Publikum war begeistert und es war ihnen auch egal, das die Er\u00f6ffnung wieder mal auf sich warten lie\u00df. Statt 19 Uhr: um 19:40 Uhr wurden die Reden geschwungen und es ging offiziell los.&nbsp; Mich freut es jedes Mal wenn eine Aktivit\u00e4t im B\u00e4renzwinger stattfindet, aber ich muss ja nicht jede gut zu finden. Aber ich war da und habe mich in der Welt der \u201eneuen\u201c Kunst versucht zurechtzufinden.<\/p>\n<p>Sigrid Schuldt<\/p>\nngg_shortcode_3_placeholder\n","protected":false},"excerpt":{"rendered":"<p>\u00bbMy Fiction and You\u00ab<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,166,157,266,167,49,3,308],"tags":[],"class_list":["post-14204","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-ausstellungen","category-berliner-baerenzwinger","category-jahr-2019","category-kunstaktionen","category-kunstler","category-topthema","category-my-fiction-and-you-2"],"_links":{"self":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts\/14204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/comments?post=14204"}],"version-history":[{"count":9,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts\/14204\/revisions"}],"predecessor-version":[{"id":14289,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts\/14204\/revisions\/14289"}],"wp:attachment":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/media?parent=14204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/categories?post=14204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/tags?post=14204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}