{"id":16671,"date":"2022-07-01T10:45:00","date_gmt":"2022-07-01T08:45:00","guid":{"rendered":"https:\/\/www.berliner-baerenfreunde.de\/web\/?p=16671"},"modified":"2022-08-03T10:47:14","modified_gmt":"2022-08-03T08:47:14","slug":"berliner-baer-berlin-wilmersdorf-im-rathaus-wilmersdorf","status":"publish","type":"post","link":"https:\/\/www.berliner-baerenfreunde.de\/web\/berliner-baer-berlin-wilmersdorf-im-rathaus-wilmersdorf\/","title":{"rendered":"Berliner B\u00e4r Berlin-Wilmersdorf im Rathaus Wilmersdorf"},"content":{"rendered":"<p>Berliner B\u00e4r von Hildebert Kliem im Wilmersdorfer Rathaus<!--more--><\/p>\nngg_shortcode_0_placeholder\n<p>Der Bronzenachguss einer B\u00e4ren-Skulptur von Hildebert Kliem (21.3.1927 &#8211; 22.3.1986) im runden Innenhof des Rathauses Wilmersdorf am Fehrbelliner Platz 4 wurde am 14. September 1988 enth\u00fcllt.<br>Der Berliner B\u00e4r ist 85 cm hoch und 33 kg schwer. Er wurde von der Bildgie\u00dferei Kraas hergestellt. Der Guss der Bronzeskulptur kostete 9915 DM. Der Sockel aus R\u00fcdersdorfer Kalkstein ist 42 cm hoch.<br>Der Abguss wurde von der Bank f\u00fcr Handel und Industrie AG zur 750-Jahrfeier-Berlins 1987 gestiftet, daran erinnert die an der Vorderseite des Sockels angebrachte rechteckige Inschriftentafel.<\/p>\n<p>&nbsp;<\/p>\n<p>Hildebert Kliem machte 1952 sein Abschlussexamen der Meisterschule f\u00fcr das Kunsthandwerk in Berlin, arbeitete als Restaurator unter anderem am Reichstag, Schloss Charlottenburg, Staatsoper Unter den Linden, Theater des Westens, M\u00e4rchenbrunnen im Friedrichshain. Ein eigenes Werk von Kliem war die Skulptur &#8222;Zwei spielende B\u00e4ren&#8220;. Der 65 cm hohe Betonguss wurde 1966 in Berlin in der &#8222;Gr\u00fcnanlage vor der Berliner Mauer&#8220;, Bernauer Stra\u00dfe, Ecke Gartenstra\u00dfe platziert.<\/p>\n<p>Quelle: Rathaus Wilmersdorf, Fehrbelliner Platz 4, 10707 Berlin<\/p>\n<p>&nbsp;<\/p>\n<p>Sieben weitere Berliner B\u00e4ren, wurden zu Lebzeiten des K\u00fcnstlers geschaffen. Das Original seines Berliner B\u00e4ren wurde vom Bund der Berliner und Freunde Berlins (BdBFB) der isl\u00e4ndischen Hauptstadt Reykjavik gestiftet und dort in einem Park 1967 aufgestellt und durch den damaligen Au\u00dfenminister Willy Brandt an die Bev\u00f6lkerung Islands \u00fcbergeben.<\/p>\n<p><br>Der B\u00e4r dort wurde zeitgleich mit dem Berliner B\u00e4ren in Ihme-Roloven (Niedersachsen, 1967) aufgestellt. Es folgten Dallas (USA, 1970), Santiago de Chile (Chile, 1972), N\u00fcmbrecht (Oberbergischer Kreis, Nordrhein-Westfalen, 1974), Helgoland (Schleswig-Holstein, 1983) und Neumarkt (Oberpfalz, 1989).<\/p>\n<p>Christa Junge<\/p>\n\n\n<p class=\"wp-block-paragraph\">ngg_shortcode_1_placeholder<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berliner B\u00e4r von Hildebert Kliem im Wilmersdorfer Rathaus<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,533,544,546,547,545,495,542,333,3],"tags":[543],"class_list":["post-16671","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-berliner-baer-von-hildebert-kliem","category-berliner-baeren-reisten-in-die-welt","category-chile","category-dallas","category-island","category-jahr-2022","category-rathaus-wilmersdorf","category-skulpturengiesserei-knaak","category-topthema","tag-berliner-baeren-reisten-in-die-welt"],"_links":{"self":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts\/16671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/comments?post=16671"}],"version-history":[{"count":20,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts\/16671\/revisions"}],"predecessor-version":[{"id":16700,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts\/16671\/revisions\/16700"}],"wp:attachment":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/media?parent=16671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/categories?post=16671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/tags?post=16671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}