{"id":18917,"date":"2024-02-14T19:09:22","date_gmt":"2024-02-14T18:09:22","guid":{"rendered":"https:\/\/www.berliner-baerenfreunde.de\/web\/?p=18917"},"modified":"2024-04-13T19:25:27","modified_gmt":"2024-04-13T17:25:27","slug":"ausstellung-16-02-28-04-2024-im-berliner-baerenzwinger","status":"publish","type":"post","link":"https:\/\/www.berliner-baerenfreunde.de\/web\/ausstellung-16-02-28-04-2024-im-berliner-baerenzwinger\/","title":{"rendered":"Ausstellung 16.02. &#8211; 28.04.2024 im                   Berliner B\u00e4renzwinger"},"content":{"rendered":"<p><!--more--><\/p>\n\n\n<p class=\"wp-block-paragraph\">Berliner B\u00e4renzwinger 16.02. &#8211; 28.04.2024  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">in<br \/>mir drau\u00dfen<br \/>derselbe Muskel: Zunge und Herz<br \/>Rike Scheffler<br \/>im Zentrum wummert<br \/>derselbe Muskel: Zunge und Herz<br \/>und bald alle einig<br \/>nicht mehr zu schweigen<br \/>hinter den H\u00e4usern<br \/>machen Wind und Licht<br \/>Gr\u00e4ser zu Gischt<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit der Ausstellung in mir drau\u00dfen stellt der B\u00e4renzwinger Berlin die Lyrik und die sich darin entfaltenden Geschichten ins Zentrum der Aufmerksamkeit. Die Duo-Ausstellung im Rahmen des Jahresprogramms 2024 KANTEN UND KNOTEN vereint Raum-, Video-, Soundund Lichtinstallationen der Lyriker*innen Nail Do\u00f0an und Rike Scheffler. Lyrik als Installation interagiert mit der Architektur des ehemaligen Tierzwingers. Sprache wird raumgreifend: drinnen und drau\u00dfen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Geschichten<br \/>Der Titel in mir drau\u00dfen verweist auf die Rolle von Geschichten, die unser Leben bestimmen und unser Zusammenleben ordnen. In dieser Hinsicht kn\u00fcpfen Geschichten Verbindungen, Relationen in und zwischen Individuen und anderen Lebewesen. Netzwerke von Personen, Orten, Zeiten genauso wie Emotionen, Affekte und Ideen stehen nebeneinander und bilden gemeinsam eine Komposition.<br \/>Hier k\u00f6nnen Fragen der Herkunft und Identit\u00e4t genauso gestellt werden wie \u00dcberlegungen zu deren zuk\u00fcnftigen Entwicklungen. Geschichten sind inkorporiert in mir, stehen aber auch drau\u00dfen in der \u00d6ffentlichkeit. So bieten Geschichten die M\u00f6glichkeit,<br \/>Grenzen des K\u00f6rpers genauso wie des individuellen oder kollektiven Horizonts zu \u00fcberwinden, um aus Trennungslinien Verbindungslinien werden zu lassen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lyrik und Raum<br \/>Die Ausstellung kreiert durch die Verbindung von Lyrik und Raum einen M\u00f6glichkeitsraum. In diesem k\u00f6nnen sich die Besucher*innen individuell und assoziativ eine Geschichte erschlie\u00dfen.<br \/>Lyrik als Kunstform kann bislang unbemerkte Zusammenh\u00e4nge sichtbar machen. Im Raum des B\u00e4renzwingers werden die lyrisch erz\u00e4hlten Geschichten greifbar, wodurch singul\u00e4re Momentaufnahmen entstehen k\u00f6nnen. M\u00f6glichkeitsr\u00e4ume drinnen und drau\u00dfen, in Sprache und Raum.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lyrik und Leselampe<br \/>Im historischen B\u00e4renzwinger erschafft in mir drau\u00dfen immersive R\u00e4ume f\u00fcr unterschiedliche Kontexte der Lyrik. In den szenografischen Positionen von Nail Do\u00f0an werden herk\u00f6mmliche Bilder der Lyrik kritisch aufgegriffen. Mit der Verwendung von wohnr\u00e4umlichen Elementen wie Sessel und Teppich verweist er auf ein popul\u00e4rkulturelles Bild von Lyrik, das diese in die Privatsph\u00e4re (innen) verortet.<br \/>Diese Repr\u00e4sentation wird durch die Positionierung in einem Tierzwinger hinterfragt und stellt gleichzeitig Fragen an die Institutionen der Lyrik. Dem gegen\u00fcber steht die immersive Video-, Licht- und Soundinstallation von Rike Scheffler. Ausgehend von der Videoinstallation Lava.Ritual kreiert Scheffler Bewegungen aus den Zellen und damit auch aus den herk\u00f6mmlichen Institutionen der Lyrik heraus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lyrisches Erz\u00e4hlen<br \/>Sprache ist Kommunikation. Intersubjektiv. Sprache entspricht gesellschaftlichen Normen, in die sich alles eingliedert, das durch Worte ausgedr\u00fcckt wird. Nuancen gehen verloren. Unsichtbares, Emotionen und ganz und gar Inneres lassen sich mit Worten nicht vollends darstellen. Realit\u00e4t kann mit Erz\u00e4hlungen nicht ad\u00e4quat abgebildet werden. Aber ohne Sprache g\u00e4be es keine Geschichten, nur eindimensionale Verbindungen zwischen uns, zwischen innen und au\u00dfen.<br \/>Lyrische Sprachverwendung sucht nach Wegen die Zwischenr\u00e4ume der Sprache auszuloten, individuelles Sprechen zu finden und gesellschaftliche Normativit\u00e4t zu durchbrechen, sie teilt sich mit in Metaphern und Analogien; Kompromisse und Neusch\u00f6pfungen, im Zeigen und Verbergen.<br \/><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lava.Ritual von Rike Scheffler<br \/>Der lyrische Kosmos von Rike Scheffler er\u00f6ffnet spielerische R\u00e4ume der F\u00fcrsorge und Konnektivit\u00e4t. Teilweise aus einer utopischen Zukunft sprechend ersetzt Rike Scheffler das gegenw\u00e4rtige Verst\u00e4ndnis von Individualit\u00e4t durch eine Relationalit\u00e4t, die Grenzen zwischen menschlichen und nichtmenschlichen Sph\u00e4ren aufl\u00f6st. Sprache wird fluide und entzieht sich dabei klassischen Vorstellungen von Lyrik.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">es ist dem Planeten egal<br \/>dass ich Sprache verwende<br \/>ihn zu beschreiten<br \/>\u2014 er w\u00e4chst<br \/>\u00fcber mich hinweg<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Verse finden sich in der immersiven Videoinstallation Lava.Ritual oder als Lichtverse, die sich Wege durch die Architektur des Zwingers suchen, sich in Wande oder Graben des Zwingers einschreiben. Die prozesshafte Morphologie der Lava steht dabei dem Backsteinbrutalismus des Barenzwingers kritisch entgegen. Der Barenzwinger, der 1939 er\u00f6ffnet wurde, ist Materialisierung der nationalsozialistischen Ideologie, die hierarchisch ist und einen ausschliesenden Charakter hat. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rike Schefflers Lava.Ritual begegnet dieser Materialitat mit einer Zartlichkeit, die die Grenzen einreist, die sich in unser Bewusstsein eingebrannt haben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">gemeinsam bilden w:r Bundel . erdgebunden:e<br \/>en\u0192\u00c3r\u0081fgi:.n als Refugium, Reservoir<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Like Lodos. von Nail Do.an<br \/>Wahrend des Produktionstreffens erwahnte Nail Do.an, er wolle sich verstecken, sich in den Zwischenraumen positionieren, in die Mauern. Doch wir wollten ihn gerne auch etwas zentraler, sichtbarer prasentieren. Ware es nach ihm gegangen, befande sich sicherlich ein Gedicht von ihm unter dem Fusabtreter. Die raumliche Positionierung von Nail Do.ans drei Lyrik-Filmen im Barenzwinger ist ein Verweis auf das, was Lyrik kann. Sie kann etwas ausdrucken, das wir vage ahnten, das wir nicht fassen oder festhalten konnten, ein Bild, ein Gesicht, das wir einmal sahen, aber vergasen: Lyrik kann etwas ins uns aufscheinen lassen. Aber sie zeigt sich uns nicht, erklart sich nicht. Sie bleibt uneindeutig: das irritiert und beruhrt. Und ergibt doch ungreifbar Sinn. Das ist es vielleicht, was uns schaudern lasst, wenn wir <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nail Do.ans Verse lesen:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">So wie. Hani. Dieses.<br \/>Wenn du Kriege in dir<br \/>nach Farben sortierst.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Geschichten in Nails Do.ans Gedichten sind alltaglich und intensiv. Denn wo . wenn nicht im Alltag, im Cafe, auf der Strase und in der eigenen Kuche . steckt es, das in-der-Weltsein?<br \/>Die Worte sind vermeintlich simpel, Nail Do.ans (lyrischen) Sprachen jedoch nicht. Roh und ausgefeilt er\u00f6ffnen seine Gedichte einen Blick in und durch die Nischen der gesellschaftlichen Struktur und hinterfragen den status quo. Nails Do.ans Werk im Barenzwinger tragt den Titel Like Lodos. Wenn ihr Nail Do.an fragt, was Lodos bedeutet, wird er so etwas sagen wie:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br \/>.Wind. Wind aus der Gegend meiner Leute. Kein<br \/>Guter. Macht Kopfschmerzen.\u0081g<br \/><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wollen wir dieselben Dinge weiterhin fur so wichtig nehmen? Fenster sind Fenster und Fuse sind auf dem Boden. Hani. Hanau. Ikiz und Hugelwind und Ingeborg\u0081f um. Die Silbe .um\u0081g bedeutet im turkischen .mein\/e\u0081g. In deutscht\u00fcrkischer Grammatik nennt Nail Do.an sein Gedicht im mittleren K\u00e4fig des Barenzwingers <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">.meine Ingeborg\u0081g und warum wir das Wort                                                                                 .postmigrantisch\u0081g doch nicht benutzen?<br \/>.Weil meine Mutter das Wort nicht kennt\u0081g.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wege Wegen<br \/>aufm Weg<br \/>wegen<br \/>Nehir<br \/>Nil<br \/>das Suchende<br \/>sucht Vulva<br \/>der Mutter<br \/>ein Fullwort<br \/>Hoffnung genau<br \/>genau<br \/>genau<br \/>im Ros.<br \/>Couscous schwimm<br \/>mich mit.<br \/>Nail Do.an<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">AUSSTELLUNG<br \/>16.02 &#8211; 28.04.2024<br \/>Kuratiert von Philipp Hennch und Joana Stamer \u00bbin mir drau\u00dfen \u00ab ist der erste Teil des Jahresprogramms KANTEN UND KNOTEN<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">VERANSTALTUNGEN<br \/>15.02.2024 ab 18 Uhr<br \/>Er\u00f6ffnung Sound Performance \u00bbEchoes from the Future\u00ab von<br \/>Rike Scheffler [19 Uhr]<br \/>Lesung<br \/>mit Nail Do?an [20 Uhr]<br \/><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">26.03.2024 ab19 Uhr<br \/>Lesung, Gespr\u00e4ch \u00bbDisplayed Words\u00ab<br \/>mit Lou Ferrand Rafael Moreno Kinga T\u00f3th<br \/><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">19.04.2024 ab 21 Uhr \u00bb Clinch \u00ab<br \/>Performance von WILD ACCESS<br \/><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">28.04.2024 16 Uhr<br \/>Finissage, Lesungen mit Nail Do?an und Rike Scheffler<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,512,699,660,697,698,695,696,3],"tags":[],"class_list":["post-18917","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-ausstellung","category-geschichten","category-jahr-2024","category-lava-ritual-von-rike-scheffler","category-like-lodos-von-nail-dogan","category-lyrik-und-raum","category-lyrisches-erzaehlen","category-topthema"],"_links":{"self":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts\/18917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/comments?post=18917"}],"version-history":[{"count":9,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts\/18917\/revisions"}],"predecessor-version":[{"id":18929,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts\/18917\/revisions\/18929"}],"wp:attachment":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/media?parent=18917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/categories?post=18917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/tags?post=18917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}