{"id":213,"date":"2008-09-17T09:47:56","date_gmt":"2008-09-17T07:47:56","guid":{"rendered":"http:\/\/www.berliner-baerenfreunde.de\/web\/?p=213"},"modified":"2011-09-22T10:18:09","modified_gmt":"2011-09-22T09:18:09","slug":"ausflug-in-den-wildpark-johannismuhle","status":"publish","type":"post","link":"https:\/\/www.berliner-baerenfreunde.de\/web\/ausflug-in-den-wildpark-johannismuhle\/","title":{"rendered":"Ausflug in den Wildpark Johannism\u00fchle"},"content":{"rendered":"<p>Am 12.September ging es f\u00fcr die B\u00e4renfreunde in den Wildpark Johannism\u00fchle.<!--more--><strong>Fahrt in den Wildpark Johannism\u00fchle<\/strong><\/p>\n<p>Am Freitag, den 12. September trafen sich Mitglieder und Freunde unseres Vereins am B\u00e4renzwinger in Mitte, um gemeinsam in den Wildpark Johannism\u00fchle zu fahren. Nur knapp eine Stunde dauerte die Fahrt mit dem Auto.<\/p>\n<p>Uns erwartete ein weitl\u00e4ufiges Gel\u00e4nde, in dem sich viele einheimische Tiere und auch ehemalige Zirkustiere, wie B\u00e4ren, L\u00f6wen und Tiger wohl f\u00fchlen. Die Tiere haben viele Paten, die den Wildpark Johannism\u00fchle bei seiner Arbeit unterst\u00fctzen.<\/p>\n<p>Als erstes beeindruckte uns die gro\u00dfe Anzahl an Dammwild, Mufflons und Ziegen die friedlich nebeneinander leben. Wir hatten Gl\u00fcck und konnten auch die F\u00fctterung dieser Tiere miterleben. Der Betreuer lie\u00df eine Glocke ert\u00f6nen und durch seinen Lockruf kamen alle zur gemeinsamen Futterstelle. Ein sehr beeindruckendes Schauspiel. Die Tiere laufen auch ohne gro\u00dfe Scheu an den Besuchern vorbei.<\/p>\n<p>Weiter ging es zu den ehemaligen Zirkusb\u00e4ren Mausi, Katja, Carla und Dolly. Sie sind zwischen 1985 bis 1989 geboren und leben jetzt mit wei\u00dfen W\u00f6lfen und Schwarzb\u00e4ren zusammen. Sie wurden vom Ehepaar Sperlich aufgezogen und traten als bekannte Longengruppe mit ihren Zieheltern im Staatszirkus der ehemaligen DDR auf. Mit der Aufl\u00f6sung des Staatszirkus der DDR verloren die B\u00e4ren ihre Existenzberechtigung. Der Wildpark Johannism\u00fchle in Zusammenarbeit mit den Deutschen Tierhilfswerk e.V. bem\u00fchte sich um den Verbleib der Tiere in Brandenburg. Seit dem 20.05.1999 haben die B\u00e4ren in dieser gro\u00dfz\u00fcgigen Freianlage eine Heimstatt gefunden. (Quelle Wildpark Johannism\u00fchle)<\/p>\n<p>Die B\u00e4ren waren neugierig und kamen durch die Freianlage bis ganz nach oben zu den Besuchern. Wir konnten sie einzeln und in guter Positur betrachten. F\u00fcr die B\u00e4ren waren wir nicht interessant genug und so liefen sie wieder zu ihren Ruhepl\u00e4tzen zur\u00fcck.<\/p>\n<p>Die n\u00e4chste Station war bei den Schwarzb\u00e4ren und dem Lux. Der Lux hatte zwei Junge, die sich spielerisch herumbalgten. Die Luxmutter lie\u00df sich von Mufflons, die direkt vor ihrer Nase \u00e4sten, ablenken. So nah, doch unerreichbar f\u00fcr sie. Durch die Besucher lie\u00dfen sich die Schwarzb\u00e4ren nicht st\u00f6ren.<\/p>\n<p>Auf unserem Rundgang sahen wir die alten Grundmauern der Johannism\u00fchle, nach der auch der Wildpark benannt wurde.<\/p>\n<p>Weiter f\u00fchrte uns der Weg zu den Vogelvolieren, u.a. mit einem Uhu, dazu alte Haustierrassen von H\u00fchnern und zwei kleinen Eichh\u00f6rnchen. Dann konnten wir Wildschweine mit ihren Jungen bewundern. Man h\u00f6rte das Br\u00fcllen des L\u00f6wen, nur wenige Meter von uns entfernt. Ganz in der N\u00e4he befindet sich die Auffangstation der Gro\u00dfkatzen. Dort leben ein L\u00f6we und zwei L\u00f6wendamen in einem gro\u00dfen Freigehege. Nebenan Tigerin Blockos, die ein tolles Freigehege ihr eigen nennt. Als wir dort waren, lag sie in ihrem offenen K\u00e4fig und schien zu schlafen.<\/p>\n<p>Nach diesem Rundgang kehrten in die Gasst\u00e4tte des Parks ein. So gest\u00e4rkt fuhren wir weiter ins Museumsdorf Glash\u00fctte. Es war sehr sehenswert, \u00fcberall im Ort gab es Glassachen zu erwerben, auch der Besuch im Glasmuseum war beeindruckend.<\/p>\n<p>Am sp\u00e4ten Nachmittag ging es zur\u00fcck nach Berlin. Ein sch\u00f6ner Tag ging f\u00fcr alle zu Ende.<\/p>\n<p><em>(Christa Junge)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 12.September ging es f\u00fcr die B\u00e4renfreunde in den Wildpark Johannism\u00fchle.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-213","post","type-post","status-publish","format-standard","hentry","category-jahr-2008"],"_links":{"self":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts\/213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/comments?post=213"}],"version-history":[{"count":6,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts\/213\/revisions"}],"predecessor-version":[{"id":1125,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/posts\/213\/revisions\/1125"}],"wp:attachment":[{"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/media?parent=213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/categories?post=213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.berliner-baerenfreunde.de\/web\/wp-json\/wp\/v2\/tags?post=213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}